{"id":1014,"date":"2017-04-12T15:42:03","date_gmt":"2017-04-12T19:42:03","guid":{"rendered":"http:\/\/elcarmelo.gob.ec\/carchi\/?p=1014"},"modified":"2017-04-12T15:42:03","modified_gmt":"2017-04-12T19:42:03","slug":"el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic","status":"publish","type":"post","link":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/","title":{"rendered":"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales.  Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos.  MOTO GUADA\u00d1A\u00a0 620 USD.  BOMBA DE FUMIGAR 80 USD.  MONTO TOTAL: 700 USD."},"content":{"rendered":"<p><a href=\"http:\/\/elcarmelo.gob.ec\/carchi\/?attachment_id=1015\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1015\" src=\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664-550x413.jpg\" alt=\"\" width=\"550\" height=\"413\" data-id=\"1015\" srcset=\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664-550x413.jpg 550w, https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664.jpg 700w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1014","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD. - GAD Parroquial de El Carmelo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD. - GAD Parroquial de El Carmelo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/\" \/>\n<meta property=\"og:site_name\" content=\"GAD Parroquial de El Carmelo\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-12T19:42:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aelcarmelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aelcarmelo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/\"},\"author\":{\"name\":\"aelcarmelo\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664\"},\"headline\":\"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD.\",\"datePublished\":\"2017-04-12T19:42:03+00:00\",\"dateModified\":\"2017-04-12T19:42:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/\"},\"wordCount\":95,\"publisher\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#organization\"},\"image\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664-550x413.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/\",\"name\":\"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD. - GAD Parroquial de El Carmelo\",\"isPartOf\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664-550x413.jpg\",\"datePublished\":\"2017-04-12T19:42:03+00:00\",\"dateModified\":\"2017-04-12T19:42:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#primaryimage\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664.jpg\",\"contentUrl\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elcarmelo.gob.ec\/carchi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD.\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#website\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/\",\"name\":\"GAD parroquial de El Carmelo\",\"description\":\"Sitio Oficial del GAD Parroquial El Carmelo Carchi\",\"publisher\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elcarmelo.gob.ec\/carchi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#organization\",\"name\":\"GAD parroquial de El Carmelo\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png\",\"contentUrl\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png\",\"width\":200,\"height\":150,\"caption\":\"GAD parroquial de El Carmelo\"},\"image\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664\",\"name\":\"aelcarmelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g\",\"caption\":\"aelcarmelo\"},\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/author\/aelcarmelo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD. - GAD Parroquial de El Carmelo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/","og_locale":"es_ES","og_type":"article","og_title":"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD. - GAD Parroquial de El Carmelo","og_url":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/","og_site_name":"GAD Parroquial de El Carmelo","article_published_time":"2017-04-12T19:42:03+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664.jpg","type":"image\/jpeg"}],"author":"aelcarmelo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aelcarmelo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#article","isPartOf":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/"},"author":{"name":"aelcarmelo","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664"},"headline":"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD.","datePublished":"2017-04-12T19:42:03+00:00","dateModified":"2017-04-12T19:42:03+00:00","mainEntityOfPage":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/"},"wordCount":95,"publisher":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#organization"},"image":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#primaryimage"},"thumbnailUrl":"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664-550x413.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/","url":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/","name":"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD. - GAD Parroquial de El Carmelo","isPartOf":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#primaryimage"},"image":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#primaryimage"},"thumbnailUrl":"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664-550x413.jpg","datePublished":"2017-04-12T19:42:03+00:00","dateModified":"2017-04-12T19:42:03+00:00","breadcrumb":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#primaryimage","url":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664.jpg","contentUrl":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/DSC03664.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-65-de-la-cootad-lit-b-planificar-construir-y-mantener-la-infraestructura-fisic\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elcarmelo.gob.ec\/carchi\/"},{"@type":"ListItem","position":2,"name":"El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 65 de la COOTAD Lit. \u00a0b) Planificar, construir y mantener la infraestructura f\u00edsica, los \u00a0equipamientos y los espacios p\u00fablicos de la parroquia, contenidos en los planes de desarrollo e incluidos en los presupuestos participativos \u00a0anuales. Se realiza la adquisici\u00f3n de una Moto guada\u00f1a y una Bomba de fumigar, herramienta\u00a0 que necesitan los trabajadores municipales para la adecuaci\u00f3n de los espacios p\u00fablicos. MOTO GUADA\u00d1A\u00a0 620 USD. BOMBA DE FUMIGAR 80 USD. MONTO TOTAL: 700 USD."}]},{"@type":"WebSite","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#website","url":"https:\/\/elcarmelo.gob.ec\/carchi\/","name":"GAD parroquial de El Carmelo","description":"Sitio Oficial del GAD Parroquial El Carmelo Carchi","publisher":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elcarmelo.gob.ec\/carchi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#organization","name":"GAD parroquial de El Carmelo","url":"https:\/\/elcarmelo.gob.ec\/carchi\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/","url":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png","contentUrl":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png","width":200,"height":150,"caption":"GAD parroquial de El Carmelo"},"image":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664","name":"aelcarmelo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g","caption":"aelcarmelo"},"url":"https:\/\/elcarmelo.gob.ec\/carchi\/author\/aelcarmelo\/"}]}},"_links":{"self":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts\/1014","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/comments?post=1014"}],"version-history":[{"count":1,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts\/1014\/revisions"}],"predecessor-version":[{"id":1016,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts\/1014\/revisions\/1016"}],"wp:attachment":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/media?parent=1014"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/categories?post=1014"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/tags?post=1014"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}