{"id":1023,"date":"2017-04-12T19:09:29","date_gmt":"2017-04-12T23:09:29","guid":{"rendered":"http:\/\/elcarmelo.gob.ec\/carchi\/?p=1023"},"modified":"2017-04-12T19:09:36","modified_gmt":"2017-04-12T23:09:36","slug":"capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas","status":"publish","type":"post","link":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/","title":{"rendered":"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit.  i) Promover y patrocinar las culturas, las artes, actividades deportivas y  recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo.  MONTO: 4800 USD"},"content":{"rendered":"<p><a href=\"http:\/\/elcarmelo.gob.ec\/carchi\/?attachment_id=1024\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-medium wp-image-1024\" src=\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n-550x310.jpg\" alt=\"\" width=\"550\" height=\"310\" data-id=\"1024\" srcset=\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n-550x310.jpg 550w, https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n.jpg 700w\" sizes=\"auto, (max-width: 550px) 100vw, 550px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":4,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1023","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD - GAD Parroquial de El Carmelo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD - GAD Parroquial de El Carmelo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/\" \/>\n<meta property=\"og:site_name\" content=\"GAD Parroquial de El Carmelo\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-12T23:09:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-04-12T23:09:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"394\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aelcarmelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aelcarmelo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/\"},\"author\":{\"name\":\"aelcarmelo\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664\"},\"headline\":\"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD\",\"datePublished\":\"2017-04-12T23:09:29+00:00\",\"dateModified\":\"2017-04-12T23:09:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/\"},\"wordCount\":69,\"publisher\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#organization\"},\"image\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n-550x310.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/\",\"name\":\"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD - GAD Parroquial de El Carmelo\",\"isPartOf\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n-550x310.jpg\",\"datePublished\":\"2017-04-12T23:09:29+00:00\",\"dateModified\":\"2017-04-12T23:09:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#primaryimage\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n.jpg\",\"contentUrl\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n.jpg\",\"width\":700,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elcarmelo.gob.ec\/carchi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#website\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/\",\"name\":\"GAD parroquial de El Carmelo\",\"description\":\"Sitio Oficial del GAD Parroquial El Carmelo Carchi\",\"publisher\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elcarmelo.gob.ec\/carchi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#organization\",\"name\":\"GAD parroquial de El Carmelo\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png\",\"contentUrl\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png\",\"width\":200,\"height\":150,\"caption\":\"GAD parroquial de El Carmelo\"},\"image\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664\",\"name\":\"aelcarmelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g\",\"caption\":\"aelcarmelo\"},\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/author\/aelcarmelo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD - GAD Parroquial de El Carmelo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/","og_locale":"es_ES","og_type":"article","og_title":"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD - GAD Parroquial de El Carmelo","og_url":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/","og_site_name":"GAD Parroquial de El Carmelo","article_published_time":"2017-04-12T23:09:29+00:00","article_modified_time":"2017-04-12T23:09:36+00:00","og_image":[{"width":700,"height":394,"url":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n.jpg","type":"image\/jpeg"}],"author":"aelcarmelo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aelcarmelo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#article","isPartOf":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/"},"author":{"name":"aelcarmelo","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664"},"headline":"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD","datePublished":"2017-04-12T23:09:29+00:00","dateModified":"2017-04-12T23:09:36+00:00","mainEntityOfPage":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/"},"wordCount":69,"publisher":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#organization"},"image":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#primaryimage"},"thumbnailUrl":"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n-550x310.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/","url":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/","name":"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD - GAD Parroquial de El Carmelo","isPartOf":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#primaryimage"},"image":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#primaryimage"},"thumbnailUrl":"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n-550x310.jpg","datePublished":"2017-04-12T23:09:29+00:00","dateModified":"2017-04-12T23:09:36+00:00","breadcrumb":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#primaryimage","url":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n.jpg","contentUrl":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2017\/04\/13509148_1131484780231056_7577857235692083880_n.jpg","width":700,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/capacitacion-de-la-banda-el-gobierno-parroquial-el-carmelo-dando-cumplimiento-con-los-acuerdos-estipulados-en-la-ley-amparados-en-el-art-64-de-la-cootad-lit-i-promover-y-patrocinar-las-culturas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elcarmelo.gob.ec\/carchi\/"},{"@type":"ListItem","position":2,"name":"CAPACITACI\u00d3N DE LA BANDA. El Gobierno Parroquial El Carmelo dando cumplimiento con los acuerdos estipulados en la ley amparados en el Art. 64 de la COOTAD Lit. i) Promover y patrocinar las culturas, las artes, actividades deportivas y recreativas en beneficio de la colectividad. Ni\u00f1os, j\u00f3venes y adultos participan activamente en la capacitaci\u00f3n del arte y cultura recreativa para incrementar una banda de pueblo. MONTO: 4800 USD"}]},{"@type":"WebSite","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#website","url":"https:\/\/elcarmelo.gob.ec\/carchi\/","name":"GAD parroquial de El Carmelo","description":"Sitio Oficial del GAD Parroquial El Carmelo Carchi","publisher":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elcarmelo.gob.ec\/carchi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#organization","name":"GAD parroquial de El Carmelo","url":"https:\/\/elcarmelo.gob.ec\/carchi\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/","url":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png","contentUrl":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png","width":200,"height":150,"caption":"GAD parroquial de El Carmelo"},"image":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664","name":"aelcarmelo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g","caption":"aelcarmelo"},"url":"https:\/\/elcarmelo.gob.ec\/carchi\/author\/aelcarmelo\/"}]}},"_links":{"self":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts\/1023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/comments?post=1023"}],"version-history":[{"count":1,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts\/1023\/revisions"}],"predecessor-version":[{"id":1025,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts\/1023\/revisions\/1025"}],"wp:attachment":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/media?parent=1023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/categories?post=1023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/tags?post=1023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}