{"id":877,"date":"2016-03-24T18:57:00","date_gmt":"2016-03-24T22:57:00","guid":{"rendered":"http:\/\/elcarmelo.gob.ec\/carchi\/?p=877"},"modified":"2017-02-21T08:07:28","modified_gmt":"2017-02-21T12:07:28","slug":"877","status":"publish","type":"post","link":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/","title":{"rendered":"Trueque de Alimentos"},"content":{"rendered":"<p>El Gobierno Parroquial de El Carmelo por primera vez realizo el trueque de alimentos con las diferentes Parroquia de nuestra Provincia como tradici\u00f2n el la Semana Santa, las Parroquias: el Goaltal, Jijon y Caama\u00f1o, Los Andes, un\u00a0agradecimiento a las Parroquia invitadas demostrando su amistad y generocidad.<a href=\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-874 \" src=\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg\" alt=\"12901041_973192906133293_1443897662523571397_o\" width=\"548\" height=\"411\" data-id=\"874\" srcset=\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg 700w, https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o-300x225.jpg 300w\" sizes=\"auto, (max-width: 548px) 100vw, 548px\" \/><\/a><!--more--><\/p>\n<p><a href=\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901215_973193082799942_2450922497620025854_o.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-873 \" src=\"http:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901215_973193082799942_2450922497620025854_o.jpg\" alt=\"12901215_973193082799942_2450922497620025854_o\" width=\"552\" height=\"414\" data-id=\"873\" srcset=\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901215_973193082799942_2450922497620025854_o.jpg 700w, https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901215_973193082799942_2450922497620025854_o-300x225.jpg 300w\" sizes=\"auto, (max-width: 552px) 100vw, 552px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Gobierno Parroquial de El Carmelo por primera vez realizo el trueque de alimentos con las diferentes Parroquia de nuestra Provincia como tradici\u00f2n el la Semana Santa, las Parroquias: el Goaltal, Jijon y Caama\u00f1o, Los Andes, un\u00a0agradecimiento a las Parroquia invitadas demostrando su amistad y generocidad.<\/p>\n","protected":false},"author":4,"featured_media":874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-877","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sin-categoria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Trueque de Alimentos - GAD Parroquial de El Carmelo<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trueque de Alimentos - GAD Parroquial de El Carmelo\" \/>\n<meta property=\"og:description\" content=\"El Gobierno Parroquial de El Carmelo por primera vez realizo el trueque de alimentos con las diferentes Parroquia de nuestra Provincia como tradici\u00f2n el la Semana Santa, las Parroquias: el Goaltal, Jijon y Caama\u00f1o, Los Andes, un\u00a0agradecimiento a las Parroquia invitadas demostrando su amistad y generocidad.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/\" \/>\n<meta property=\"og:site_name\" content=\"GAD Parroquial de El Carmelo\" \/>\n<meta property=\"article:published_time\" content=\"2016-03-24T22:57:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-02-21T12:07:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"525\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aelcarmelo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"aelcarmelo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/\"},\"author\":{\"name\":\"aelcarmelo\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664\"},\"headline\":\"Trueque de Alimentos\",\"datePublished\":\"2016-03-24T22:57:00+00:00\",\"dateModified\":\"2017-02-21T12:07:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/\"},\"wordCount\":52,\"publisher\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#organization\"},\"image\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg\",\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/\",\"name\":\"Trueque de Alimentos - GAD Parroquial de El Carmelo\",\"isPartOf\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg\",\"datePublished\":\"2016-03-24T22:57:00+00:00\",\"dateModified\":\"2017-02-21T12:07:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#primaryimage\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg\",\"contentUrl\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg\",\"width\":700,\"height\":525},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/elcarmelo.gob.ec\/carchi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trueque de Alimentos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#website\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/\",\"name\":\"GAD parroquial de El Carmelo\",\"description\":\"Sitio Oficial del GAD Parroquial El Carmelo Carchi\",\"publisher\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elcarmelo.gob.ec\/carchi\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#organization\",\"name\":\"GAD parroquial de El Carmelo\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png\",\"contentUrl\":\"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png\",\"width\":200,\"height\":150,\"caption\":\"GAD parroquial de El Carmelo\"},\"image\":{\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664\",\"name\":\"aelcarmelo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g\",\"caption\":\"aelcarmelo\"},\"url\":\"https:\/\/elcarmelo.gob.ec\/carchi\/author\/aelcarmelo\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Trueque de Alimentos - GAD Parroquial de El Carmelo","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/","og_locale":"es_ES","og_type":"article","og_title":"Trueque de Alimentos - GAD Parroquial de El Carmelo","og_description":"El Gobierno Parroquial de El Carmelo por primera vez realizo el trueque de alimentos con las diferentes Parroquia de nuestra Provincia como tradici\u00f2n el la Semana Santa, las Parroquias: el Goaltal, Jijon y Caama\u00f1o, Los Andes, un\u00a0agradecimiento a las Parroquia invitadas demostrando su amistad y generocidad.","og_url":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/","og_site_name":"GAD Parroquial de El Carmelo","article_published_time":"2016-03-24T22:57:00+00:00","article_modified_time":"2017-02-21T12:07:28+00:00","og_image":[{"width":700,"height":525,"url":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg","type":"image\/jpeg"}],"author":"aelcarmelo","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"aelcarmelo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#article","isPartOf":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/"},"author":{"name":"aelcarmelo","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664"},"headline":"Trueque de Alimentos","datePublished":"2016-03-24T22:57:00+00:00","dateModified":"2017-02-21T12:07:28+00:00","mainEntityOfPage":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/"},"wordCount":52,"publisher":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#organization"},"image":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#primaryimage"},"thumbnailUrl":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg","inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/","url":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/","name":"Trueque de Alimentos - GAD Parroquial de El Carmelo","isPartOf":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#primaryimage"},"image":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#primaryimage"},"thumbnailUrl":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg","datePublished":"2016-03-24T22:57:00+00:00","dateModified":"2017-02-21T12:07:28+00:00","breadcrumb":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elcarmelo.gob.ec\/carchi\/877\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#primaryimage","url":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg","contentUrl":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2016\/03\/12901041_973192906133293_1443897662523571397_o.jpg","width":700,"height":525},{"@type":"BreadcrumbList","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/877\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/elcarmelo.gob.ec\/carchi\/"},{"@type":"ListItem","position":2,"name":"Trueque de Alimentos"}]},{"@type":"WebSite","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#website","url":"https:\/\/elcarmelo.gob.ec\/carchi\/","name":"GAD parroquial de El Carmelo","description":"Sitio Oficial del GAD Parroquial El Carmelo Carchi","publisher":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elcarmelo.gob.ec\/carchi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#organization","name":"GAD parroquial de El Carmelo","url":"https:\/\/elcarmelo.gob.ec\/carchi\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/","url":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png","contentUrl":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-content\/uploads\/2020\/06\/logoFooter-Recuperado.png","width":200,"height":150,"caption":"GAD parroquial de El Carmelo"},"image":{"@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/199546f2b0966330a5c8d044c25b5664","name":"aelcarmelo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/elcarmelo.gob.ec\/carchi\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4849cead80a540a505e4f16b1e4cbabb?s=96&d=mm&r=g","caption":"aelcarmelo"},"url":"https:\/\/elcarmelo.gob.ec\/carchi\/author\/aelcarmelo\/"}]}},"_links":{"self":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts\/877","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/comments?post=877"}],"version-history":[{"count":4,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts\/877\/revisions"}],"predecessor-version":[{"id":904,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/posts\/877\/revisions\/904"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/media\/874"}],"wp:attachment":[{"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/media?parent=877"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/categories?post=877"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/elcarmelo.gob.ec\/carchi\/wp-json\/wp\/v2\/tags?post=877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}